{"id":218,"count":3,"description":"","link":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/","name":"Die Kekse","slug":"die-kekse","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Kekse Archivi - La Fabbrica del Panforte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Kekse Archivi - La Fabbrica del Panforte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/\" \/>\n<meta property=\"og:site_name\" content=\"La Fabbrica del Panforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/categoria-prodotto\\\/die-kekse\\\/\",\"url\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/categoria-prodotto\\\/die-kekse\\\/\",\"name\":\"Die Kekse Archivi - La Fabbrica del Panforte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/categoria-prodotto\\\/die-kekse\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/categoria-prodotto\\\/die-kekse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/die-panforte-manufaktur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Kekse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/\",\"name\":\"La Fabbrica del Panforte\",\"description\":\"Dolci tipici senesi\",\"publisher\":{\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/#organization\",\"name\":\"La Fabbrica del Panforte\",\"url\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_laFabbricadelPanforte.webp\",\"contentUrl\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo_laFabbricadelPanforte.webp\",\"width\":2560,\"height\":1949,\"caption\":\"La Fabbrica del Panforte\"},\"image\":{\"@id\":\"https:\\\/\\\/lafabbricadelpanforte.sviluppo.host\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Kekse Archivi - La Fabbrica del Panforte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/","og_locale":"de_DE","og_type":"article","og_title":"Die Kekse Archivi - La Fabbrica del Panforte","og_url":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/","og_site_name":"La Fabbrica del Panforte","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/","url":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/","name":"Die Kekse Archivi - La Fabbrica del Panforte","isPartOf":{"@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/#website"},"breadcrumb":{"@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/categoria-prodotto\/die-kekse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/die-panforte-manufaktur\/"},{"@type":"ListItem","position":2,"name":"Die Kekse"}]},{"@type":"WebSite","@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/#website","url":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/","name":"La Fabbrica del Panforte","description":"Dolci tipici senesi","publisher":{"@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/#organization","name":"La Fabbrica del Panforte","url":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/#\/schema\/logo\/image\/","url":"https:\/\/lafabbricadelpanforte.sviluppo.host\/wp-content\/uploads\/2026\/06\/logo_laFabbricadelPanforte.webp","contentUrl":"https:\/\/lafabbricadelpanforte.sviluppo.host\/wp-content\/uploads\/2026\/06\/logo_laFabbricadelPanforte.webp","width":2560,"height":1949,"caption":"La Fabbrica del Panforte"},"image":{"@id":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/wp-json\/wp\/v2\/product_cat\/218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/lafabbricadelpanforte.sviluppo.host\/de\/wp-json\/wp\/v2\/product?product_cat=218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}